{"id":62105,"date":"2025-04-30T17:40:06","date_gmt":"2025-04-30T15:40:06","guid":{"rendered":"https:\/\/pilma.com\/product\/set-de-2-taules-de-centre-juno-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/"},"modified":"2026-09-01T06:15:29","modified_gmt":"2026-09-01T04:15:29","slug":"set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca","status":"publish","type":"product","link":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/","title":{"rendered":"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":62098,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[5014],"product_cat":[910,1233,4003],"product_tag":[],"class_list":["post-62105","product","type-product","status-publish","has-post-thumbnail","product_brand-plm-design","product_cat-taules","product_cat-taules-de-centre","product_cat-taules-rodones","pa_altura-35-ca","pa_coleccion-juso-ca","pa_diametro-75-ca","pa_material-acer-lacat","pa_material-teca-reciclada-ca","pa_peso-0-ca","pa_requiere-montaje-no","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca - Pilma - Mobles de disseny i decoraci\u00f3 d&#039;interiors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca - Pilma - Mobles de disseny i decoraci\u00f3 d&#039;interiors\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/\" \/>\n<meta property=\"og:site_name\" content=\"Pilma - Mobles de disseny i decoraci\u00f3 d&#039;interiors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pilma.es\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T04:15:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pilma.com\/wp-content\/uploads\/2024\/11\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"2200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@pilma_es\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/\",\"url\":\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/\",\"name\":\"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca - Pilma - Mobles de disseny i decoraci\u00f3 d'interiors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pilma.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg\",\"datePublished\":\"2025-04-30T15:40:06+00:00\",\"dateModified\":\"2026-09-01T04:15:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pilma.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg\",\"contentUrl\":\"https:\\\/\\\/pilma.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg\",\"width\":1900,\"height\":2200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/producte\\\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pilma.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botigues &#8211; Todos los productos\",\"item\":\"https:\\\/\\\/pilma.com\\\/ca\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/pilma.com\\\/ca\\\/\",\"name\":\"Pilma - Mobles de disseny i decoraci\u00f3 d'interiors\",\"description\":\"Pilma - Mobles de disseny i decoraci\u00f3 d'interiors\",\"publisher\":{\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pilma.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/#organization\",\"name\":\"Pilma\",\"url\":\"https:\\\/\\\/pilma.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pilma.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Pilma-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/pilma.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Pilma-512x512-1.png\",\"width\":512,\"height\":512,\"caption\":\"Pilma\"},\"image\":{\"@id\":\"https:\\\/\\\/pilma.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pilma.es\\\/\",\"https:\\\/\\\/x.com\\\/pilma_es\",\"https:\\\/\\\/www.instagram.com\\\/pilma.es\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/pilma-es\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/pilma_es\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca - Pilma - Mobles de disseny i decoraci\u00f3 d'interiors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/","og_locale":"ca_ES","og_type":"article","og_title":"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca - Pilma - Mobles de disseny i decoraci\u00f3 d'interiors","og_url":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/","og_site_name":"Pilma - Mobles de disseny i decoraci\u00f3 d'interiors","article_publisher":"https:\/\/www.facebook.com\/Pilma.es\/","article_modified_time":"2026-09-01T04:15:29+00:00","og_image":[{"width":1900,"height":2200,"url":"https:\/\/pilma.com\/wp-content\/uploads\/2024\/11\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@pilma_es","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/","url":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/","name":"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca - Pilma - Mobles de disseny i decoraci\u00f3 d'interiors","isPartOf":{"@id":"https:\/\/pilma.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/#primaryimage"},"image":{"@id":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/#primaryimage"},"thumbnailUrl":"https:\/\/pilma.com\/wp-content\/uploads\/2024\/11\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg","datePublished":"2025-04-30T15:40:06+00:00","dateModified":"2026-09-01T04:15:29+00:00","breadcrumb":{"@id":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/#primaryimage","url":"https:\/\/pilma.com\/wp-content\/uploads\/2024\/11\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg","contentUrl":"https:\/\/pilma.com\/wp-content\/uploads\/2024\/11\/0714-JU075050-SET-2-MESAS-CENTRO-JUNO-75-50-PILMA-01.jpg","width":1900,"height":2200},{"@type":"BreadcrumbList","@id":"https:\/\/pilma.com\/ca\/producte\/set-de-2-taules-de-centre-juso-o-75-x-35-cm-i-o-50-x-31-cm-de-teca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pilma.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Botigues &#8211; Todos los productos","item":"https:\/\/pilma.com\/ca\/tienda\/"},{"@type":"ListItem","position":3,"name":"Set de 2 taules de centre Juso\u00a0\u00d8\u00a075 x 35 cm i\u00a0\u00d8\u00a050 x 31 cm de teca"}]},{"@type":"WebSite","@id":"https:\/\/pilma.com\/ca\/#website","url":"https:\/\/pilma.com\/ca\/","name":"Pilma - Mobles de disseny i decoraci\u00f3 d'interiors","description":"Pilma - Mobles de disseny i decoraci\u00f3 d'interiors","publisher":{"@id":"https:\/\/pilma.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pilma.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/pilma.com\/ca\/#organization","name":"Pilma","url":"https:\/\/pilma.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/pilma.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/pilma.com\/wp-content\/uploads\/2025\/11\/Pilma-512x512-1.png","contentUrl":"https:\/\/pilma.com\/wp-content\/uploads\/2025\/11\/Pilma-512x512-1.png","width":512,"height":512,"caption":"Pilma"},"image":{"@id":"https:\/\/pilma.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pilma.es\/","https:\/\/x.com\/pilma_es","https:\/\/www.instagram.com\/pilma.es\/","https:\/\/es.linkedin.com\/company\/pilma-es\/","https:\/\/www.pinterest.es\/pilma_es\/"]}]}},"_links":{"self":[{"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/product\/62105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/media\/62098"}],"wp:attachment":[{"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/media?parent=62105"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/product_brand?post=62105"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/product_cat?post=62105"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pilma.com\/ca\/wp-json\/wp\/v2\/product_tag?post=62105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}